{"id":7535,"date":"2022-08-24T10:10:00","date_gmt":"2022-08-24T08:10:00","guid":{"rendered":"https:\/\/www.coffeemakers.de\/wpcm\/?p=7535"},"modified":"2022-08-23T08:57:08","modified_gmt":"2022-08-23T06:57:08","slug":"kaffeesatz-als-wespenschreck","status":"publish","type":"post","link":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/","title":{"rendered":"Kaffeesatz als Wespenschreck"},"content":{"rendered":"\n<p>Sie sitzen auf einer sch\u00f6nen Terrasse &#8211; im besten Fall noch mit Kaffee und Kuchen. Aber zur Ruhe kommen Sie nicht, denn Wespen wollen auch etwas von Ihrem Gl\u00fcck. Mit altem Kaffeesatz halten Sie die Wespen einfach fern.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Wespen haben grunds\u00e4tzlich zwei Phasen pro Jahr &#8211; in der ersten Phase jagen sie vor allem andere Insekten oder wollen beim Grillabend auch etwas Fleisch bekommen. In dieser Zeit k\u00fcmmern sich die Tiere um ihre Larven, die viel Eiwei\u00df zum Wachsen brauchen. Diese Phase der Brutpflege wird deshalb auch herzhafte Phase genannt.<\/p>\n\n\n\n<p>In der zweiten Phase, meist beginnend im Sp\u00e4tsommer und Herbst, werden auch s\u00fc\u00dfe Speisen wie vergorene Fr\u00fcchte aber auch Kuchen und Softdrinks interessant. Da die Brutpflege nicht mehr so viel Zeit in Anspruch nimmt, achten die Wespen mehr auf ihren Genuss. Experten sprechen von der s\u00fc\u00dfen Phase.<\/p>\n\n\n\n<p>Durch diese zwei Phasen haben wir aber kaum Pausen vor Wespen, beim Grillen aber auch beim Kaffee und Kuchen kann man mit Wespen als ungebetenen G\u00e4sten rechnen. Da Wespen zus\u00e4tzlich sehr kurzsichtig sind, erkennen sie uns Menschen nicht direkt &#8211; und je n\u00e4her eine Wespe kommt, umso hektischer werden in der Regel die Abwehrbewegungen. Hektische Bewegungen machen die Wespe allerdings aggressiv und das Risiko gestochen zu werden vergr\u00f6\u00dfert sich. Eine tote Wespe verbreitet zus\u00e4tzlich noch nach ihrem Tod Pheromone, welche weitere Artgenossen anlockt.<\/p>\n\n\n<h2 class=\"wp-block-heading\" id=\"kaffeesatz-als-loesung-gegen-wespen\">Kaffeesatz als L\u00f6sung gegen Wespen<\/h2>\n\n\n<p>Eben weil Wespen sehr schlecht sehen, ist ihr Riechinstinkt sehr ausgepr\u00e4gt. Es ist also durchaus einen Versuch wert, den gesammelten alten Kaffeesatz zu trocknen und f\u00fcr die Wespenbek\u00e4mpfung zu sammeln.<\/p>\n\n\n\n<p>Geben Sie etwa 3 &#8211; 5 Essl\u00f6ffel des getrockneten Kaffeesatzes in einen feuerfesten Beh\u00e4lter und z\u00fcnden den Kaffeesatz dann an. Es sollte nicht wirklich brennen, sondern nur leicht vor sich her qualmen und leicht glimmen. Der Rauch hat ein sehr intensives Aroma, welches Wespen und andere Fliegen nicht m\u00f6gen.<\/p>\n\n\n\n<p>Je nach eigenem Geschmack k\u00f6nnen Sie hingegen den Rauch sogar m\u00f6gen, so wie die frisch gebr\u00fchte Tasse Kaffee. Je nach Standort und Windrichtung k\u00f6nnen Sie den Beh\u00e4lter so positionieren, dass Sie selbst gem\u00fctlich drau\u00dfen Zeit verbringen k\u00f6nnen, ohne \u00fcberm\u00e4\u00dfig gest\u00f6rt zu werden.<\/p>\n\n\n\n<p>Die 3 &#8211; 5 Essl\u00f6ffel Kaffeesatz sollten rund zwei Stunden ausreichen und Ihnen gen\u00fcgend Ruhe verschaffen. Nat\u00fcrlich k\u00f6nnen Sie auch frisch gemahlenen Kaffee verwenden, wenn es schnell gehen muss &#8211; dann aber lieber immer etwas Kaffeesatz trocknen und aufheben.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.coffeemakers.de\/kaffee\/espresso-marese-kaffee?utm_source=wpcm&amp;utm_medium=kafboh&amp;utm_campaign=kafbohallg&amp;utm_id=120\"><img loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"90\" src=\"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/01\/728-marese-1.jpg\" alt=\"Marese Banner - Link zu Maresekaffee.\" class=\"wp-image-5857\" srcset=\"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/01\/728-marese-1.jpg 728w, https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/01\/728-marese-1-300x37.jpg 300w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><figcaption><a href=\"https:\/\/www.coffeemakers.de\/kaffee\/espresso-marese-kaffee?utm_source=wpcm&amp;utm_medium=kafboh&amp;utm_campaign=kafbohallg&amp;utm_id=120\">Marese ist unsere Kaffeebohneneigenmarke &#8211; verschiedene Geschmacksrichtungen <strong>in unserem Onlineshop<\/strong><\/a><\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sie sitzen auf einer sch\u00f6nen Terrasse &#8211; im besten Fall noch mit Kaffee und Kuchen. Aber zur Ruhe kommen Sie nicht, denn Wespen wollen auch etwas von Ihrem Gl\u00fcck. Mit altem Kaffeesatz halten Sie die Wespen einfach fern.<\/p>\n","protected":false},"author":3,"featured_media":7537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[338,337],"class_list":["post-7535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coffeemakers-magazin","tag-kaffeesatz-gegen-wespen","tag-wespen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kaffeesatz als Wespenschreck - Coffeemakers Magazin<\/title>\n<meta name=\"description\" content=\"Wespen sind oft ungeladene G\u00e4ste - beim Grillen oder Kaffee und Kuchen \u2192 mit Kaffeesatz k\u00f6nnen Sie Wespen einfach vertreiben\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kaffeesatz als Wespenschreck - Coffeemakers Magazin\" \/>\n<meta property=\"og:description\" content=\"Wespen sind oft ungeladene G\u00e4ste - beim Grillen oder Kaffee und Kuchen \u2192 mit Kaffeesatz k\u00f6nnen Sie Wespen einfach vertreiben\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/\" \/>\n<meta property=\"og:site_name\" content=\"Coffeemakers Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-24T08:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/08\/wasp-4496602_1280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coffeemakers Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coffeemakers Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/\"},\"author\":{\"name\":\"Coffeemakers Redaktion\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#\\\/schema\\\/person\\\/982e146c82954ad9882cc636b386af81\"},\"headline\":\"Kaffeesatz als Wespenschreck\",\"datePublished\":\"2022-08-24T08:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/wasp-4496602_1280-1.jpg\",\"keywords\":[\"Kaffeesatz gegen Wespen\",\"Wespen\"],\"articleSection\":[\"Coffeemakers Magazin\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/\",\"name\":\"Kaffeesatz als Wespenschreck - Coffeemakers Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/wasp-4496602_1280-1.jpg\",\"datePublished\":\"2022-08-24T08:10:00+00:00\",\"description\":\"Wespen sind oft ungeladene G\u00e4ste - beim Grillen oder Kaffee und Kuchen \u2192 mit Kaffeesatz k\u00f6nnen Sie Wespen einfach vertreiben\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/wasp-4496602_1280-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/wasp-4496602_1280-1.jpg\",\"width\":1024,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/kaffeesatz-als-wespenschreck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kaffeesatz als Wespenschreck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#website\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/\",\"name\":\"Coffeemakers Magazin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#organization\",\"name\":\"Coffeemakers Magazin\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/coffeemakers-logo-2018.png\",\"contentUrl\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/coffeemakers-logo-2018.png\",\"width\":2723,\"height\":2723,\"caption\":\"Coffeemakers Magazin\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/#\\\/schema\\\/person\\\/982e146c82954ad9882cc636b386af81\",\"name\":\"Coffeemakers Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-cropped-coffeemakers-logo-2018-96x96.png\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-cropped-coffeemakers-logo-2018-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-cropped-coffeemakers-logo-2018-96x96.png\",\"caption\":\"Coffeemakers Redaktion\"},\"description\":\"Die Redaktion von Coffeemakers.de liefert ihnen alle Daten, Fakten und Hintergrundinfos, die ein Kaffeeliebhaber und stolzer Besitzer eines Kaffeevollautomaten braucht. Egal ob es dabei um den Kaffee selbst geht, seine Zubereitung, was gerade auf dem Markt f\u00fcr Kaffeevollautomaten los ist oder wie Sie dank guter Wartung und Pflege lange Freude an ihrem eigenen Ger\u00e4t haben.\",\"url\":\"https:\\\/\\\/www.coffeemakers.de\\\/wpcm\\\/author\\\/coffeemakers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kaffeesatz als Wespenschreck - Coffeemakers Magazin","description":"Wespen sind oft ungeladene G\u00e4ste - beim Grillen oder Kaffee und Kuchen \u2192 mit Kaffeesatz k\u00f6nnen Sie Wespen einfach vertreiben","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/","og_locale":"de_DE","og_type":"article","og_title":"Kaffeesatz als Wespenschreck - Coffeemakers Magazin","og_description":"Wespen sind oft ungeladene G\u00e4ste - beim Grillen oder Kaffee und Kuchen \u2192 mit Kaffeesatz k\u00f6nnen Sie Wespen einfach vertreiben","og_url":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/","og_site_name":"Coffeemakers Magazin","article_published_time":"2022-08-24T08:10:00+00:00","og_image":[{"width":1024,"height":380,"url":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/08\/wasp-4496602_1280-1.jpg","type":"image\/jpeg"}],"author":"Coffeemakers Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Coffeemakers Redaktion","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#article","isPartOf":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/"},"author":{"name":"Coffeemakers Redaktion","@id":"https:\/\/www.coffeemakers.de\/wpcm\/#\/schema\/person\/982e146c82954ad9882cc636b386af81"},"headline":"Kaffeesatz als Wespenschreck","datePublished":"2022-08-24T08:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/#organization"},"image":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/08\/wasp-4496602_1280-1.jpg","keywords":["Kaffeesatz gegen Wespen","Wespen"],"articleSection":["Coffeemakers Magazin"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/","url":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/","name":"Kaffeesatz als Wespenschreck - Coffeemakers Magazin","isPartOf":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#primaryimage"},"image":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/08\/wasp-4496602_1280-1.jpg","datePublished":"2022-08-24T08:10:00+00:00","description":"Wespen sind oft ungeladene G\u00e4ste - beim Grillen oder Kaffee und Kuchen \u2192 mit Kaffeesatz k\u00f6nnen Sie Wespen einfach vertreiben","breadcrumb":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#primaryimage","url":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/08\/wasp-4496602_1280-1.jpg","contentUrl":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2022\/08\/wasp-4496602_1280-1.jpg","width":1024,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/www.coffeemakers.de\/wpcm\/kaffeesatz-als-wespenschreck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.coffeemakers.de\/wpcm\/"},{"@type":"ListItem","position":2,"name":"Kaffeesatz als Wespenschreck"}]},{"@type":"WebSite","@id":"https:\/\/www.coffeemakers.de\/wpcm\/#website","url":"https:\/\/www.coffeemakers.de\/wpcm\/","name":"Coffeemakers Magazin","description":"","publisher":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coffeemakers.de\/wpcm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.coffeemakers.de\/wpcm\/#organization","name":"Coffeemakers Magazin","url":"https:\/\/www.coffeemakers.de\/wpcm\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.coffeemakers.de\/wpcm\/#\/schema\/logo\/image\/","url":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2023\/06\/coffeemakers-logo-2018.png","contentUrl":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2023\/06\/coffeemakers-logo-2018.png","width":2723,"height":2723,"caption":"Coffeemakers Magazin"},"image":{"@id":"https:\/\/www.coffeemakers.de\/wpcm\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.coffeemakers.de\/wpcm\/#\/schema\/person\/982e146c82954ad9882cc636b386af81","name":"Coffeemakers Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2023\/06\/cropped-cropped-coffeemakers-logo-2018-96x96.png","url":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2023\/06\/cropped-cropped-coffeemakers-logo-2018-96x96.png","contentUrl":"https:\/\/www.coffeemakers.de\/wpcm\/wp-content\/uploads\/2023\/06\/cropped-cropped-coffeemakers-logo-2018-96x96.png","caption":"Coffeemakers Redaktion"},"description":"Die Redaktion von Coffeemakers.de liefert ihnen alle Daten, Fakten und Hintergrundinfos, die ein Kaffeeliebhaber und stolzer Besitzer eines Kaffeevollautomaten braucht. Egal ob es dabei um den Kaffee selbst geht, seine Zubereitung, was gerade auf dem Markt f\u00fcr Kaffeevollautomaten los ist oder wie Sie dank guter Wartung und Pflege lange Freude an ihrem eigenen Ger\u00e4t haben.","url":"https:\/\/www.coffeemakers.de\/wpcm\/author\/coffeemakers\/"}]}},"_links":{"self":[{"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/posts\/7535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/comments?post=7535"}],"version-history":[{"count":2,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/posts\/7535\/revisions"}],"predecessor-version":[{"id":7545,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/posts\/7535\/revisions\/7545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/media\/7537"}],"wp:attachment":[{"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/media?parent=7535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/categories?post=7535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coffeemakers.de\/wpcm\/wp-json\/wp\/v2\/tags?post=7535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}